{"id":11001,"date":"2022-05-13T13:58:20","date_gmt":"2022-05-13T13:58:20","guid":{"rendered":"https:\/\/k2-systems.com\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/"},"modified":"2025-08-15T06:43:54","modified_gmt":"2025-08-15T04:43:54","slug":"informativa-sulla-privacy-del-servizio-di-autenticazione-k2","status":"publish","type":"page","link":"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/","title":{"rendered":"Informativa sulla privacy del Servizio di autenticazione K2"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":0,"parent":54273,"menu_order":910,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-11001","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informativa sulla privacy del Servizio di autenticazione K2 - K2 Systems<\/title>\n<meta name=\"description\" content=\"Leggete qui la nostra informativa sulla privacy per il servizio di autenticazione K2 single sign-on.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativa sulla privacy del Servizio di autenticazione K2\" \/>\n<meta property=\"og:description\" content=\"Leggete qui la nostra informativa sulla privacy per il servizio di autenticazione K2 single sign-on.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/\" \/>\n<meta property=\"og:site_name\" content=\"K2 Systems\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-15T04:43:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/servizi-digitali\\\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\\\/\",\"url\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/servizi-digitali\\\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\\\/\",\"name\":\"Informativa sulla privacy del Servizio di autenticazione K2 - K2 Systems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/#website\"},\"datePublished\":\"2022-05-13T13:58:20+00:00\",\"dateModified\":\"2025-08-15T04:43:54+00:00\",\"description\":\"Leggete qui la nostra informativa sulla privacy per il servizio di autenticazione K2 single sign-on.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/servizi-digitali\\\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k2-systems.com\\\/it\\\/servizi-digitali\\\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/servizi-digitali\\\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi digitali\",\"item\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/servizi-digitali\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Informativa sulla privacy del Servizio di autenticazione K2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/\",\"name\":\"K2 Systems\",\"description\":\"K2 Systems WP\",\"publisher\":{\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/#organization\",\"name\":\"K2 Systems\",\"url\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/k2-systems.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_512x512.png\",\"contentUrl\":\"https:\\\/\\\/k2-systems.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/logo_512x512.png\",\"width\":512,\"height\":512,\"caption\":\"K2 Systems\"},\"image\":{\"@id\":\"https:\\\/\\\/k2-systems.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informativa sulla privacy del Servizio di autenticazione K2 - K2 Systems","description":"Leggete qui la nostra informativa sulla privacy per il servizio di autenticazione K2 single sign-on.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/","og_locale":"it_IT","og_type":"article","og_title":"Informativa sulla privacy del Servizio di autenticazione K2","og_description":"Leggete qui la nostra informativa sulla privacy per il servizio di autenticazione K2 single sign-on.","og_url":"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/","og_site_name":"K2 Systems","article_modified_time":"2025-08-15T04:43:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/","url":"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/","name":"Informativa sulla privacy del Servizio di autenticazione K2 - K2 Systems","isPartOf":{"@id":"https:\/\/k2-systems.com\/it\/#website"},"datePublished":"2022-05-13T13:58:20+00:00","dateModified":"2025-08-15T04:43:54+00:00","description":"Leggete qui la nostra informativa sulla privacy per il servizio di autenticazione K2 single sign-on.","breadcrumb":{"@id":"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k2-systems.com\/it\/servizi-digitali\/informativa-sulla-privacy-del-servizio-di-autenticazione-k2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/k2-systems.com\/it\/"},{"@type":"ListItem","position":2,"name":"Servizi digitali","item":"https:\/\/k2-systems.com\/it\/servizi-digitali\/"},{"@type":"ListItem","position":3,"name":"Informativa sulla privacy del Servizio di autenticazione K2"}]},{"@type":"WebSite","@id":"https:\/\/k2-systems.com\/it\/#website","url":"https:\/\/k2-systems.com\/it\/","name":"K2 Systems","description":"K2 Systems WP","publisher":{"@id":"https:\/\/k2-systems.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k2-systems.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/k2-systems.com\/it\/#organization","name":"K2 Systems","url":"https:\/\/k2-systems.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/k2-systems.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/k2-systems.com\/wp-content\/uploads\/2022\/02\/logo_512x512.png","contentUrl":"https:\/\/k2-systems.com\/wp-content\/uploads\/2022\/02\/logo_512x512.png","width":512,"height":512,"caption":"K2 Systems"},"image":{"@id":"https:\/\/k2-systems.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/k2-systems.com\/it\/wp-json\/wp\/v2\/pages\/11001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k2-systems.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k2-systems.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k2-systems.com\/it\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/k2-systems.com\/it\/wp-json\/wp\/v2\/comments?post=11001"}],"version-history":[{"count":0,"href":"https:\/\/k2-systems.com\/it\/wp-json\/wp\/v2\/pages\/11001\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/k2-systems.com\/it\/wp-json\/wp\/v2\/pages\/54273"}],"wp:attachment":[{"href":"https:\/\/k2-systems.com\/it\/wp-json\/wp\/v2\/media?parent=11001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}